                       {"id":58714,"date":"2024-07-01T14:10:32","date_gmt":"2024-07-01T20:10:32","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=58714"},"modified":"2024-07-01T14:10:32","modified_gmt":"2024-07-01T20:10:32","slug":"primeros-249-jubilados-del-imss-reciben-complementos-del-fondo-de-pensiones-para-el-bienestar","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/primeros-249-jubilados-del-imss-reciben-complementos-del-fondo-de-pensiones-para-el-bienestar\/","title":{"rendered":"Primeros 249 jubilados del IMSS reciben complementos del Fondo de Pensiones para el Bienestar"},"content":{"rendered":"<p>\u2022 Delfina Calder\u00f3n, quien labor\u00f3 durante 55 a\u00f1os, y Raymundo Vallejo, extrabajador de Ruta 100, entre los primeros de un universo de beneficiaros que se beneficiar\u00e1n<\/p>\n<p>\u2022 El director general del IMSS, Zo\u00e9 Robledo, informa que entre el 2 de mayo y el 14 de junio se recibieron 335 resoluciones de pensi\u00f3n de vejez<\/p>\n<p>\u2022 Para tr\u00e1mites en IMSS se habilitaron mil 537 ventanillas \u00fanicas en Unidades de Medicina Familiar y subdelegaciones<\/p>\n<p>&nbsp;<\/p>\n<p>El gobierno federal entreg\u00f3 hoy los primeros complementos del Fondo de Pensiones para el Bienestar a 249 jubilados que cotizaron al amparo de la Ley del Seguro Social de 1997, con lo que recibieron el 100 por ciento de su \u00faltimo salario registrado ante el Instituto Mexicano del Seguro Social (IMSS).<\/p>\n<p>&nbsp;<\/p>\n<p>Durante la conferencia de prensa en Palacio Nacional, el presidente Andr\u00e9s Manuel L\u00f3pez Obrador entreg\u00f3 de manera simb\u00f3lica los complementos de pensi\u00f3n a Delfina Calder\u00f3n y Raymundo Vallejo.<\/p>\n<p>&nbsp;<\/p>\n<p>El director general del IMSS, Zo\u00e9 Robledo, destac\u00f3 que la creaci\u00f3n del Fondo de Pensiones para el Bienestar tiene rostros de personas, que despu\u00e9s de a\u00f1os de trabajo recibir\u00e1n una jubilaci\u00f3n m\u00e1s justa, como la Delfina Calder\u00f3n, quien trabaj\u00f3 durante 55 a\u00f1os, 29 para el gobierno en la Subsecretar\u00eda de Planeaci\u00f3n y 26 en la iniciativa privada.<\/p>\n<p>&nbsp;<\/p>\n<p>Record\u00f3 que el pasado 18 de marzo comenz\u00f3 el tr\u00e1mite de su pensi\u00f3n a los 72 a\u00f1os, despu\u00e9s de mil 247 semanas de cotizaci\u00f3n y con un \u00faltimo salario de 12 mil 289 pesos.<\/p>\n<p>&nbsp;<\/p>\n<p>Refiri\u00f3 que, sin el apoyo brindado por el gobierno federal, Delfina hubiera recibido una pensi\u00f3n de siete mil 489 pesos; ahora tendr\u00e1 un complemento de cuatro mil 800 pesos para alcanzar el equivalente a su \u00faltimo salario.<\/p>\n<p>&nbsp;<\/p>\n<p>Expuso el caso de Raymundo Vallejo, quien desde los 19 a\u00f1os trabaj\u00f3 en el sector transportista de la Ciudad de M\u00e9xico y form\u00f3 parte de la Ruta 100. Hoy, con 72 a\u00f1os y mil 18 semanas de cotizar en el Seguro Social, obtuvo su pensi\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Precis\u00f3 que, con un salario de 13 mil 77 pesos al mes, sin la reforma su pensi\u00f3n hubiera sido de cinco mil 628 pesos, pero a trav\u00e9s del Fondo de Pensiones para el Bienestar recibir\u00e1 un complemento de siete mil 449 pesos.<\/p>\n<p>&nbsp;<\/p>\n<p>Detall\u00f3 que entre el 2 de mayo y el 14 de junio se recibieron 335 resoluciones de pensi\u00f3n de vejez expedidas al amparo de la Ley del Seguro Social de 1997.<\/p>\n<p>&nbsp;<\/p>\n<p>De estas, 249 reciben desde hoy el complemento a su pensi\u00f3n; 99.2 por ciento lo har\u00e1n a trav\u00e9s de una afore, adem\u00e1s de dos casos de renta vitalicia. El pago promedio del complemento es de tres mil 975 pesos y la tasa de reemplazo pas\u00f3 de 57 a 96 por ciento.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEste universo seguir\u00e1 creciendo a lo largo de los meses y de los a\u00f1os, hay complementos desde 179 pesos, que son peque\u00f1os, pero tambi\u00e9n los hay de 11 mil 160 pesos, que es hasta el momento el m\u00e1s alto que se ha recibido.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>A\u00f1adi\u00f3 que son 989 mil pesos hasta el momento lo que significa el pago de estos complementos, \u201cir\u00e1 increment\u00e1ndose a lo largo del tiempo y afortunadamente ya se tienen los recursos\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Explic\u00f3 que las personas que cotizaban al Seguro Social tendr\u00e1n disponibles las ventanillas \u00fanicas para tr\u00e1mites en mil 537 puntos del pa\u00eds; se ubican en mil 404 Unidades de Medicina Familiar (UMF) y en 133 Subdelegaciones del IMSS.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-58716\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/05-300x193.jpg\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/05-300x193.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/05-1024x659.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/05-768x494.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/05-1536x989.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/05-2048x1319.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-58717\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/08-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/08-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/08-1024x683.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/08-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/08-1536x1024.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/08-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-58718\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/02-300x190.jpg\" alt=\"\" width=\"300\" height=\"190\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/02-300x190.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/02-1024x649.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/02-768x486.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/02-1536x973.jpg 1536w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/02-2048x1297.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Se\u00f1al\u00f3 que tambi\u00e9n est\u00e1 disponible la aplicaci\u00f3n Mi Pensi\u00f3n Digital, a trav\u00e9s de la p\u00e1gina electr\u00f3nica tspi.imss.gob.mx, donde las personas pueden recibir informaci\u00f3n, conocer sobre los tr\u00e1mites y saber si son parte del universo de beneficiarios del Fondo de Pensiones para el Bienestar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Delfina Calder\u00f3n, quien labor\u00f3 durante 55 a\u00f1os, y Raymundo Vallejo, extrabajador de Ruta 100, entre los primeros de un universo de beneficiaros que se beneficiar\u00e1n \u2022 El director general del IMSS, Zo\u00e9 Robledo, informa que entre el 2 de mayo y el 14 de junio se recibieron 335 resoluciones de pensi\u00f3n de vejez \u2022 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":58715,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[1249,3590,5859],"class_list":["post-58714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-imss","tag-juarez-nl","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/58714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=58714"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/58714\/revisions"}],"predecessor-version":[{"id":58719,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/58714\/revisions\/58719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/58715"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=58714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=58714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=58714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}