                       {"id":58978,"date":"2024-07-10T13:21:33","date_gmt":"2024-07-10T19:21:33","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=58978"},"modified":"2024-07-10T13:21:33","modified_gmt":"2024-07-10T19:21:33","slug":"cuenta-imss-nuevo-leon-con-equipamiento-de-alta-tecnologia-para-diagnostico-y-tratamientos-oncologicos-en-umae-no-25","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/cuenta-imss-nuevo-leon-con-equipamiento-de-alta-tecnologia-para-diagnostico-y-tratamientos-oncologicos-en-umae-no-25\/","title":{"rendered":"Cuenta IMSS Nuevo Le\u00f3n con equipamiento de alta tecnolog\u00eda para diagn\u00f3stico y tratamientos oncol\u00f3gicos en UMAE No. 25"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>\u2022 Recibi\u00f3 Hospital de Especialidades un acelerador lineal, un mast\u00f3grafo y dos ultrason\u00f3grafos.<\/p>\n<p>\u2022 Invirti\u00f3 el Instituto 112.4 millones de pesos en adquisici\u00f3n de equipos para atenci\u00f3n oncol\u00f3gica.<\/p>\n<p>\u2022 Aument\u00f3 UMAE No. 25 capacidad de atenci\u00f3n para los 9 millones de derechohabientes de Nuevo Le\u00f3n, Coahuila, Tamaulipas y San Luis Potos\u00ed.<\/p>\n<p>Con una inversi\u00f3n de 112.4 millones de pesos, el Instituto Mexicano del Seguro Social (IMSS) trabaja con nuevo equipamiento de alta tecnolog\u00eda para el diagn\u00f3stico y tratamiento de c\u00e1ncer en la Unidad M\u00e9dica de Alta Especialidad (UMAE) Hospital de Especialidades No. 25, en Nuevo Le\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Entre los nuevos equipos se encuentran un acelerador lineal, un mast\u00f3grafo y dos ultrason\u00f3grafos.<\/p>\n<p>&nbsp;<\/p>\n<p>Como parte del Programa Nacional de Adquisiciones del IMSS en el 2023, la UMAE No. 25 obtuvo un acelerador lineal, con valor de 107.1 millones de pesos, con capacidad para brindar radioterapia a mil 400 pacientes oncol\u00f3gicos por mes. El equipo se suma al conjunto de tres aceleradores ya instalados.<\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s, se puso en operaci\u00f3n un nuevo mast\u00f3grafo, con una inversi\u00f3n de m\u00e1s de 2 millones 682 mil pesos, con el que se atienden de 50 a 100 pacientes mensuales para diagn\u00f3sticos precisos y seguimiento oportuno en tratamientos de c\u00e1ncer de mama.<\/p>\n<p>&nbsp;<\/p>\n<p>Del mismo modo, con el uso de tecnolog\u00eda 4D para el abordaje de diversos procedimientos de radiolog\u00eda intervencionista, la UMAE No. 25 recibi\u00f3 dos nuevos equipos de ultrasonido, con un costo tambi\u00e9n de m\u00e1s de 2 millones 603 mil pesos, capaces de realizar hasta 2 mil 400 estudios mensuales.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-58980\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/Screenshot_20240710-130404-300x189.png\" alt=\"\" width=\"300\" height=\"189\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/Screenshot_20240710-130404-300x189.png 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/Screenshot_20240710-130404-1024x644.png 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/Screenshot_20240710-130404-768x483.png 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/Screenshot_20240710-130404.png 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-58981\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/Screenshot_20240710-130417-300x193.png\" alt=\"\" width=\"300\" height=\"193\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/Screenshot_20240710-130417-300x193.png 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/Screenshot_20240710-130417-1024x659.png 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/Screenshot_20240710-130417-768x494.png 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/07\/Screenshot_20240710-130417.png 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Estos esfuerzos para adquirir equipamiento de alta tecnolog\u00eda permiten a la UMAE Hospital de Especialidades No. 25 del IMSS incrementar su capacidad de atenci\u00f3n a una poblaci\u00f3n de aproximadamente 9 millones de derechohabientes de Nuevo Le\u00f3n, Coahuila, Tamaulipas y San Luis Potos\u00ed.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u2022 Recibi\u00f3 Hospital de Especialidades un acelerador lineal, un mast\u00f3grafo y dos ultrason\u00f3grafos. \u2022 Invirti\u00f3 el Instituto 112.4 millones de pesos en adquisici\u00f3n de equipos para atenci\u00f3n oncol\u00f3gica. \u2022 Aument\u00f3 UMAE No. 25 capacidad de atenci\u00f3n para los 9 millones de derechohabientes de Nuevo Le\u00f3n, Coahuila, Tamaulipas y San Luis Potos\u00ed. Con una inversi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":58979,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[1249,5859],"class_list":["post-58978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-imss","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/58978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=58978"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/58978\/revisions"}],"predecessor-version":[{"id":58982,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/58978\/revisions\/58982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/58979"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=58978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=58978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=58978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}