                       {"id":59582,"date":"2024-07-27T17:37:27","date_gmt":"2024-07-27T23:37:27","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=59582"},"modified":"2024-07-27T17:37:27","modified_gmt":"2024-07-27T23:37:27","slug":"hieren-a-balazos-a-uno-en-las-concordias","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/hieren-a-balazos-a-uno-en-las-concordias\/","title":{"rendered":"Hieren a balazos a uno en Las Concordias"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Ju\u00e1rez, N.L.-Un hombre result\u00f3 herido tras recibir dos impactos de bala, esto en la calle Coral, en el domicilio marcado con el n\u00famero 607 de la colonia Las Concordias, en el municipio de Ju\u00e1rez.<br \/>\nAnteriormente se reportaban dos personas ejecutadas, pero al llegar las autoridades esta informaci\u00f3n qued\u00f3 descartada, al arribo de los param\u00e9dicos de Protecci\u00f3n Civil al mando del director Francisco Moyar, quienes localizaron caminando err\u00e1tico en el lugar, a un hombre, quien refiri\u00f3 ser el lesionado.<br \/>\nLa v\u00edctima, quien fue identificada c\u00f3mo Brayan Ulises Ramos Ramos, de 26 a\u00f1os de edad, presentaba un impacto en la mand\u00edbula y uno m\u00e1s en el hombro izquierdo<br \/>\nEl herido fue trasladado a un hospital para su atenci\u00f3n m\u00e9dica, aunque se descart\u00f3 que laa lesiones pusieran en riesgo su vida.<br \/>\nHasta el momento se desconoce el paradero de los responsables y el m\u00f3vil del ataque, por lo que se dio una intensa movilizaci\u00f3n por parte de la polic\u00eda municipal y agentes ministeriales, quienes iniciaron las investigaciones correspondientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Ju\u00e1rez, N.L.-Un hombre result\u00f3 herido tras recibir dos impactos de bala, esto en la calle Coral, en el domicilio marcado con el n\u00famero 607 de la colonia Las Concordias, en el municipio de Ju\u00e1rez. Anteriormente se reportaban dos personas ejecutadas, pero al llegar las autoridades esta informaci\u00f3n qued\u00f3 descartada, al arribo de los param\u00e9dicos [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":59583,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,10],"tags":[4351,1191,1355,4218],"class_list":["post-59582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-seguridad","category-seguridad-juarez","tag-balazos","tag-herido","tag-juarez","tag-policia"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/59582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=59582"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/59582\/revisions"}],"predecessor-version":[{"id":59584,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/59582\/revisions\/59584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/59583"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=59582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=59582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=59582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}