                       {"id":59913,"date":"2024-08-07T14:35:25","date_gmt":"2024-08-07T20:35:25","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=59913"},"modified":"2024-08-07T14:35:25","modified_gmt":"2024-08-07T20:35:25","slug":"inaugura-paco-trevino-nuevo-centro-de-atencion-infantil","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/inaugura-paco-trevino-nuevo-centro-de-atencion-infantil\/","title":{"rendered":"Inaugura Paco Trevi\u00f1o nuevo centro de atenci\u00f3n infantil\u00a0"},"content":{"rendered":"<p>Con mejores instalaciones para mayor seguridad y comodidad de los ni\u00f1os, el Alcalde de Ju\u00e1rez, Francisco Trevi\u00f1o Cant\u00fa, encabez\u00f3 la inauguraci\u00f3n del nuevo Centro de Atenci\u00f3n Infantil (CAI) en la zona Centro del municipio.<\/p>\n<p>&#8220;El d\u00eda de hoy cumplimos otro m\u00e1s de nuestros compromisos y cristalizamos el sue\u00f1o de habilitar un nuevo Centro de Atenci\u00f3n Infantil con mejores instalaciones para mayor comodidad de los peque\u00f1os y m\u00e1s tranquilidad para todos los padres de familia&#8221;, expres\u00f3 Paco Trevi\u00f1o.<\/p>\n<p>Adem\u00e1s hizo un reconocimiento a la labor realizada por todo el equipo del DIF municipal (encargado de las estancias infantiles) y a su esposa Adriana de la Garza, presidenta de esta instituci\u00f3n.<\/p>\n<p>&#8220;Gracias a todo el equipo del DIF de Ju\u00e1rez, Nuevo Le\u00f3n, y a mi esposa Adri de la Garza, presidenta de esta instituci\u00f3n, por su dedicaci\u00f3n y entrega en favor de los ni\u00f1os de Ju\u00e1rez&#8221;, dijo el Alcalde.<\/p>\n<p>Durante el evento de inauguraci\u00f3n se resalt\u00f3 que las seis estancias infantiles municipales que maneja el DIF de Ju\u00e1rez son totalmente inclusivas, ya que se acepta a ni\u00f1os con discapacidades.<\/p>\n<p>Adem\u00e1s, en cuatro de estas guarder\u00edas se imparte a los peque\u00f1os el nivel preescolar, siendo \u00e9stas las ubicadas en las colonias Real de San Jos\u00e9, Arcadia, Anzures y zona Centro.<\/p>\n<p>Las otras dos estancias infantiles se ubican en las colonias Monteverde y Santa M\u00f3nica.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-59915\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0018-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0018-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0018-1024x683.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0018-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0018.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-59916\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0015-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0015-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0015-1024x683.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0015-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0015.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-59917\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0017-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0017-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0017-1024x683.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0017-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0017.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-59918\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0016-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0016-300x200.jpg 300w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0016-1024x683.jpg 1024w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0016-768x512.jpg 768w, https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2024\/08\/IMG-20240807-WA0016.jpg 1080w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con mejores instalaciones para mayor seguridad y comodidad de los ni\u00f1os, el Alcalde de Ju\u00e1rez, Francisco Trevi\u00f1o Cant\u00fa, encabez\u00f3 la inauguraci\u00f3n del nuevo Centro de Atenci\u00f3n Infantil (CAI) en la zona Centro del municipio. &#8220;El d\u00eda de hoy cumplimos otro m\u00e1s de nuestros compromisos y cristalizamos el sue\u00f1o de habilitar un nuevo Centro de Atenci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":59914,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[1684,5859],"class_list":["post-59913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-paco-trevino","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/59913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=59913"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/59913\/revisions"}],"predecessor-version":[{"id":59919,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/59913\/revisions\/59919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/59914"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=59913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=59913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=59913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}