                       {"id":5993,"date":"2019-01-30T15:24:39","date_gmt":"2019-01-30T15:24:39","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=5993"},"modified":"2024-12-11T08:53:38","modified_gmt":"2024-12-11T14:53:38","slug":"unen-esfuerzos-dif-cadereyta-y-region-8","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/unen-esfuerzos-dif-cadereyta-y-region-8\/","title":{"rendered":"Unen esfuerzos DIF Cadereyta y Regi\u00f3n 8"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5995 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/01\/50917487_2197014773676720_8330474148769824768_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/>Cadereyta Jim\u00e9nez, N.L.- Con el motivo de solucionar problem\u00e1ticas que acontecen de manera frecuente en diversos planteles educativos de este municipio, Martha de la Garza, Presidenta del Sistema DIF Cadereyta, acompa\u00f1ada de la Directora de la misma dependencia Blanca Flores, sostuvieron una reuni\u00f3n con la Profesora Martha Rivera de la Cerda, Jefa de la Unidad Regional 8.<br \/>\nEn dicha reuni\u00f3n, acordaron unir esfuerzos para implementar medidas preventivas, as\u00ed como la manera de brindar alternativas para evitar situaciones de riesgo entre la poblaci\u00f3n estudiantil, con la finalidad de garantizar que el estudiante mantenga su objetivo de tener \u00e9xito en la escuela.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadereyta Jim\u00e9nez, N.L.- Con el motivo de solucionar problem\u00e1ticas que acontecen de manera frecuente en diversos planteles educativos de este municipio, Martha de la Garza, Presidenta del Sistema DIF Cadereyta, acompa\u00f1ada de la Directora de la misma dependencia Blanca Flores, sostuvieron una reuni\u00f3n con la Profesora Martha Rivera de la Cerda, Jefa de la Unidad [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":5994,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[308,850,1505,1506,1951],"class_list":["post-5993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","tag-blanca-flores","tag-dif-cadereyta","tag-martha-de-la-garza-de-quintanilla","tag-martha-rivero-de-la-cerda","tag-region-8"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/5993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=5993"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/5993\/revisions"}],"predecessor-version":[{"id":66218,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/5993\/revisions\/66218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=5993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=5993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=5993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}