                       {"id":60375,"date":"2024-08-22T12:51:51","date_gmt":"2024-08-22T18:51:51","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=60375"},"modified":"2024-08-22T12:51:51","modified_gmt":"2024-08-22T18:51:51","slug":"ejecutan-a-dos-en-distintos-puntos-de-garcia","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/ejecutan-a-dos-en-distintos-puntos-de-garcia\/","title":{"rendered":"Ejecutan a dos en distintos puntos de Garc\u00eda"},"content":{"rendered":"<p>GARC\u00cdA, Nuevo Le\u00f3n.- La muerte sigue trabajando a marchas forzadas en el \u00e1rea metropolitana de Monterrey; las escenas del crimen ahora fueron delimitadas en el municipio de Garc\u00eda.<\/p>\n<p>Hallazgos realizados por la ciudadan\u00eda llevaron a las autoridades a descubrir dos ejecuciones. El primero de los hechos violentos se dio poco antes de las 7:00 de la ma\u00f1ana cerca de las calles Del Refugio y 27 de Octubre, de la colonia Paseo de Capellan\u00eda v\u00eda el 9-1-1 alertaban de una persona en un terreno bald\u00edo.<\/p>\n<p>A la llegada de la Polic\u00eda Municipal y personal m\u00e9dico encontraron al hombre de unos 40 a\u00f1os inconsciente y con sangre en rostro, ya no contaba signos vitales.<\/p>\n<p>La v\u00edctima no fue identificada solo se dijo llevaba una camisa roja con estampado de baseball, pantal\u00f3n de mezclilla azul y botas caf\u00e9s, llevaba 2 tatuajes, uno de ellos en antebrazo izquierdo con la leyenda de \u201cSayra\u201d y otro con la palabra \u201cNaomi\u201d.<\/p>\n<p>El segundo hallazgo se dio una hora m\u00e1s tarde; una llamada a la l\u00ednea de emergencia ahora llevaba a la polic\u00eda a una zona ferroviaria aleda\u00f1a a la colonia Valle de Lincoln, sector Fraile.<\/p>\n<p>La Polic\u00eda Municipal llega al sitio y confirma la ejecuci\u00f3n, el var\u00f3n de unos 25 a\u00f1os ten\u00eda heridas provocadas por proyectiles de arma de fuego.<\/p>\n<p>Tampoco fue identificado oficialmente, solo se dijo llevaba camisa gris, pantal\u00f3n gris oscuro y calzado negro, al momento de encontrar su cad\u00e1ver se le encontr\u00f3 con una gorra en la mano izquierda, adem\u00e1s estaba tatuado en cuello y rostro.<\/p>\n<p>FUENTE: POSTA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GARC\u00cdA, Nuevo Le\u00f3n.- La muerte sigue trabajando a marchas forzadas en el \u00e1rea metropolitana de Monterrey; las escenas del crimen ahora fueron delimitadas en el municipio de Garc\u00eda. Hallazgos realizados por la ciudadan\u00eda llevaron a las autoridades a descubrir dos ejecuciones. El primero de los hechos violentos se dio poco antes de las 7:00 de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":60376,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[924,8144,5859],"class_list":["post-60375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-ejecutados","tag-garcia","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/60375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=60375"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/60375\/revisions"}],"predecessor-version":[{"id":60377,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/60375\/revisions\/60377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/60376"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=60375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=60375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=60375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}