                       {"id":60540,"date":"2024-08-27T14:06:55","date_gmt":"2024-08-27T20:06:55","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=60540"},"modified":"2024-08-27T14:06:55","modified_gmt":"2024-08-27T20:06:55","slug":"cae-con-moto-y-mota","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/cae-con-moto-y-mota\/","title":{"rendered":"Cae con moto y mota"},"content":{"rendered":"<p>Ju\u00e1rez, N.L.<\/p>\n<p>En la tarde de ayer, su forma de conducir delat\u00f3 a sun sujeto, quien aparte de traer varias bolsas con marihuana, la motocicleta que conduc\u00eda ten\u00eda reporte de robo.<\/p>\n<p>Una unidad de Seguridad P\u00fablica se desplazaba sobre la avenida Las Torres en su cruce con la calle Magnolia en el fraccionamiento Las Concordias, cuando sus tripulantes visualizarlo a un motociclista conduciendo a exceso de velocidad y en forma imprudente.<\/p>\n<p>Los oficiales le marcaron el alto al conductor, quien hizo caso omiso, inici\u00e1ndose una persecuci\u00f3n que culmin\u00f3 cerca del lugar, cuando el sujeto cay\u00f3 al suelo al derrapar la motocicleta, para enseguida levantarse y tratar de huir corriendo, , pero de inmediato fue asegurado por los uniformados.<\/p>\n<p>Los polic\u00edas de inmediato iniciaron el interrogatorio y al realizarle una revisi\u00f3n corporal le encontraron 13 envoltorios con marihuana, 18 envoltorios de pl\u00e1stico de &#8220;cristal&#8221; y un radio de comunicaci\u00f3n.<\/p>\n<p>Los polic\u00edas revisaron con el C4 el n\u00famero de serie de la motocicleta y dio positivo en reporte de robo.<\/p>\n<p>En ese momento Eleazar Z. de 32 a\u00f1os, fue puesto a disposici\u00f3n de la autoridad competente junto con el narc\u00f3tico y el veh\u00edculo asegurado para que le sea resuelta su situaci\u00f3n jur\u00eddica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ju\u00e1rez, N.L. En la tarde de ayer, su forma de conducir delat\u00f3 a sun sujeto, quien aparte de traer varias bolsas con marihuana, la motocicleta que conduc\u00eda ten\u00eda reporte de robo. Una unidad de Seguridad P\u00fablica se desplazaba sobre la avenida Las Torres en su cruce con la calle Magnolia en el fraccionamiento Las Concordias, [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":60541,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[819,3590,5859],"class_list":["post-60540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-detenido","tag-juarez-nl","tag-ultimas-noticias"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/60540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=60540"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/60540\/revisions"}],"predecessor-version":[{"id":60542,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/60540\/revisions\/60542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/60541"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=60540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=60540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=60540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}