                       {"id":6189,"date":"2019-02-08T02:11:03","date_gmt":"2019-02-08T02:11:03","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=6189"},"modified":"2024-12-11T08:53:41","modified_gmt":"2024-12-11T14:53:41","slug":"el-inst-de-la-mujer-no-se-cierra-eq","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/el-inst-de-la-mujer-no-se-cierra-eq\/","title":{"rendered":"\u201cEl Inst. de la Mujer  no se cierra\u201d: EQ"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-6191 alignright\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/02\/base1-7-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/>Miguel Oscar P\u00e9rez<br \/>\n\u201cEl Instituto de la Mujer no se cierra, el Instituto de la mujer es una necesidad que tenemos aqu\u00ed en Cadereyta, hay que recordar la violencia de g\u00e9nero en el estado y m\u00e1s en el municipio estamos en alerta\u201d, expres\u00f3 Ernesto Quintanilla.<br \/>\nEl alcalde dijo en rueda de prensa, que no es una desaparici\u00f3n, sino una fusi\u00f3n que tendr\u00e1n las mismas funciones y responsabilidades.<br \/>\n\u201cEs una fusi\u00f3n donde le estamos dando, en primera instancia m\u00e1s espacio al Instituto como la direcci\u00f3n. Tambi\u00e9n se est\u00e1 fusionando con el CADIM que hace la misma funci\u00f3n que hace la misma funci\u00f3n que el Instituto de la Mujer\u201d, explic\u00f3 Quintanilla Villarreal.<br \/>\nA\u00f1adi\u00f3 que lo hab\u00eda dicho en campa\u00f1a que iba a fusionar varias dependencias que estaban haciendo doble funci\u00f3n.<br \/>\nComo beneficio de lo anterior bajaron sueldos, bajaron espacios de renta y los recursos ahorrados sirvan para darle m\u00e1s atenci\u00f3n al Instituto de la Mujer, as\u00ed como el CADIM y la Casa de D\u00eda del Adulto Mayor.<br \/>\nLo anterior despu\u00e9s de la pol\u00e9mica generada en el sentido que tanto Cadereyta como Apodaca, convert\u00edan los institutos de la Mujer en direcciones.<br \/>\nEn ese sentido Martha Cecilia Reyes, titular del Instituto de las Mujeres en el estado, exhorto a Apodaca como a Cadereyta por la supuesta conversi\u00f3n de institutos a direcciones.<br \/>\nLa funcionaria alega que la personalidad de Instituto cumple con las reglamentaciones internacionales y no las direcciones en las que fueron cambiadas.<br \/>\nLa medida tambi\u00e9n tuvo eco en el Congreso del Estado, al solicitar la diputada Karina Barr\u00f3n en tribuna, enviar un exhorto a los alcalde de Cadereyta y Apodaca.<br \/>\nSin embargo el alcalde dijo que est\u00e1n previstas todas las funciones y responsabilidades del Instituto, pero ahora fusionados con otras dependencias que cumpl\u00edan las mismas funciones.<br \/>\n&#8220;Ya en conjunto con el Instituto de la Mujer vemos el bienestar en general. Muchas veces se piensa \u00bfpor qu\u00e9 no hay un instituto del hombre si tambi\u00e9n son violentados?, por eso es el punto de nosotros como DIF de ver todo desde un punto m\u00e1s neutral y un panorama de m\u00e1s amplio en bienestar, tanto de la mujer, como de los hijos y los caballeros&#8221;, dijo Blanca Flores, la directora del DIF municipal.<br \/>\nPrometen las autoridades municipales que estar\u00e1n atentos sobre la violencia de g\u00e9nero, ya que Cadereyta es uno de los municipios con m\u00e1s incidencias en ese tipo al igual que Ju\u00e1rez, Guadalupe y Monterrey.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miguel Oscar P\u00e9rez \u201cEl Instituto de la Mujer no se cierra, el Instituto de la mujer es una necesidad que tenemos aqu\u00ed en Cadereyta, hay que recordar la violencia de g\u00e9nero en el estado y m\u00e1s en el municipio estamos en alerta\u201d, expres\u00f3 Ernesto Quintanilla. El alcalde dijo en rueda de prensa, que no es [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":6190,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[990,1295,1493,1505],"class_list":["post-6189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","tag-ernesto-quintanilla","tag-instituto-municipal-de-la-mujer-cadereyta","tag-maria-del-rosario-carrasco-lopez","tag-martha-de-la-garza-de-quintanilla"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/6189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=6189"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/6189\/revisions"}],"predecessor-version":[{"id":66326,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/6189\/revisions\/66326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=6189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=6189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=6189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}