                       {"id":62137,"date":"2024-11-14T00:07:14","date_gmt":"2024-11-14T06:07:14","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=62137"},"modified":"2024-11-14T00:07:14","modified_gmt":"2024-11-14T06:07:14","slug":"alumno-dispara-4rma-de-fuego-en-salon-de-clases-en-torreon-coahuila","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/alumno-dispara-4rma-de-fuego-en-salon-de-clases-en-torreon-coahuila\/","title":{"rendered":"Alumno dispara 4rma de fuego en sal\u00f3n de clases en Torre\u00f3n, Coahuila"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Un alumno de cuarto de primaria alarm\u00f3 a la comunidad estudiantil en Torre\u00f3n, Coahuila cuando dispar\u00f3 un arma de fuego al interior de un sal\u00f3n de clases; la bala peg\u00f3 en el pizarr\u00f3n.<\/p>\n<p>El incidente ocurri\u00f3 en la escuela primaria \u201cA\u00f1o de Ju\u00e1rez ubicada en la esquina de la calle Heroico Colegio Militar y bulevar \u00c1guila Nacional, del sector Centro.<\/p>\n<p>De acuerdo a la Secretar\u00eda de Seguridad P\u00fablica, en el hecho no se reportaron personas lesionadas.<\/p>\n<p>Las autoridades escolares dialogaron con el menor de edad y lograron asegurarle el arma de fuego.<\/p>\n<p>La informaci\u00f3n fue confirmada primero por la escuela a trav\u00e9s de un comunicado en Facebook y despu\u00e9s la propia secretar\u00eda de Seguridad P\u00fablica.<\/p>\n<p>Por su parte la fiscal\u00eda general de Coahuila inici\u00f3 una carpeta de investigaci\u00f3n para determinar la procedencia del arma y establecer la responsabilidad legal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Un alumno de cuarto de primaria alarm\u00f3 a la comunidad estudiantil en Torre\u00f3n, Coahuila cuando dispar\u00f3 un arma de fuego al interior de un sal\u00f3n de clases; la bala peg\u00f3 en el pizarr\u00f3n. El incidente ocurri\u00f3 en la escuela primaria \u201cA\u00f1o de Ju\u00e1rez ubicada en la esquina de la calle Heroico Colegio Militar y [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":62121,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-62137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/62137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=62137"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/62137\/revisions"}],"predecessor-version":[{"id":62138,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/62137\/revisions\/62138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/62121"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=62137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=62137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=62137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}