                       {"id":8372,"date":"2019-06-03T15:23:25","date_gmt":"2019-06-03T20:23:25","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=8372"},"modified":"2024-12-11T08:55:51","modified_gmt":"2024-12-11T14:55:51","slug":"reconocen-mujeres-que-participaron-en-red-de-mujeres-cadereyta-2019","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/reconocen-mujeres-que-participaron-en-red-de-mujeres-cadereyta-2019\/","title":{"rendered":"Reconocen mujeres que participaron en &#8220;Red de Mujeres Cadereyta 2019&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\">\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8373 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/06\/61648228_481194896031047_6545784820599881728_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/>Cadereyta Jim\u00e9nez, N. L.- El Centro para el Desarrollo de las Mujeres, del Instituto Estatal de las Mujeres, realiz\u00f3 la clausura de pl\u00e1ticas para las j\u00f3venes estudiantes del Instituto Vinton en Cadereyta y entreg\u00f3 reconocimientos a las mujeres adolescentes que participaron la ma\u00f1ana del pasado 30 de mayo.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8375 alignright\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/06\/62220062_335700453763964_2627972295217381376_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/>Durante 2 meses y medio, se estuvo trabajando en conferencias acerca de la violencia en el noviazgo, la autoestima, el empoderamiento de la mujer, as\u00ed como de derechos humanos y discriminaci\u00f3n, para prevenir y orientar a las mujeres, con la finalidad de crear una Red de Mujeres por parte de dicho centro.<br \/>\nSe hizo la entrega de reconocimientos por parte de representantes del DIF Cadereyta, el IMM y la Casa de D\u00eda del Adulto Mayor, as\u00ed como del CDM y del Instituto Vinton.<br \/>\nEsta actividad es realizada en conjunto con el Instituto Municipal de las Mujeres, como parte de las acciones que se llevan a cabo, en la Administraci\u00f3n 2018-2021.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Cadereyta Jim\u00e9nez, N. L.- El Centro para el Desarrollo de las Mujeres, del Instituto Estatal de las Mujeres, realiz\u00f3 la clausura de pl\u00e1ticas para las j\u00f3venes estudiantes del Instituto Vinton en Cadereyta y entreg\u00f3 reconocimientos a las mujeres adolescentes que participaron la ma\u00f1ana del pasado 30 de mayo. Durante 2 meses y medio, se estuvo [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":8374,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[308,1295,2047],"class_list":["post-8372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","tag-blanca-flores","tag-instituto-municipal-de-la-mujer-cadereyta","tag-rosario-carrasco-lopez"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/8372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=8372"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/8372\/revisions"}],"predecessor-version":[{"id":67467,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/8372\/revisions\/67467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=8372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=8372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=8372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}