                       {"id":9174,"date":"2019-07-21T20:21:38","date_gmt":"2019-07-22T01:21:38","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=9174"},"modified":"2024-12-11T08:56:02","modified_gmt":"2024-12-11T14:56:02","slug":"integran-comite-de-participacion-ciudadana-en-real-de-cadereyta","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/integran-comite-de-participacion-ciudadana-en-real-de-cadereyta\/","title":{"rendered":"Integran Comit\u00e9 de Participaci\u00f3n Ciudadana en Real de Cadereyta"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9176 alignright\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/07\/67304371_2476982189013309_8989296340697612288_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/> Cadereyta Jim\u00e9nez, N.L.-<br \/>\nPara seguir formando el v\u00ednculo entre sociedad y gobierno, personal de la Administraci\u00f3n 2018-2021, a trav\u00e9s de la Direcci\u00f3n de Participaci\u00f3n Ciudadana, conformaron el comit\u00e9 n\u00famero 21 con el fin de ir trabajando en las principales necesidades de este sector y resolverlas a la brevedad posible.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9177 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/07\/67425471_2476982239013304_5454587270256394240_n-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/> Carlos Rafael Rodr\u00edguez G\u00f3mez, Secretario de Ayuntamiento, asisti\u00f3 a la formaci\u00f3n de comit\u00e9 y tom\u00f3 la protesta de ley a los integrantes que los mismos vecinos eligieron.<br \/>\nSiendo el Comit\u00e9 de participaci\u00f3n ciudadana colonia Real de Cadereyta conformado por:<br \/>\n1.- Presidenta:<br \/>\nMar\u00eda del Pilar Garc\u00eda D\u00edaz<br \/>\n2.- Secretaria:<br \/>\nBeatriz Arenas Valencia<br \/>\n3.- Vocal 1<br \/>\nOlivia Margarita Aguirre<br \/>\n4.- Vocal 2<br \/>\nJos\u00e9 Alfredo Henestrosa<br \/>\n5.- Vocal 3<br \/>\nSoledad Gabriela Rodr\u00edguez<br \/>\n6.- Vocal 4<br \/>\nGabriela Hern\u00e1ndez Garc\u00eda<\/p>\n<p style=\"text-align: justify;\">M\u00f3nica Trevi\u00f1o Sada, Directora de Participaci\u00f3n Ciudadana, agradeci\u00f3 a los presentes por estar interesados en formar parte de estos grupos, donde la intenci\u00f3n principal es hacer sinergia con el gobierno municipal, atendiendo la instrucci\u00f3n de Ernesto Quintanilla Villarreal, Alcalde de Cadereyta de estar siempre en contacto con la ciudadan\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cadereyta Jim\u00e9nez, N.L.- Para seguir formando el v\u00ednculo entre sociedad y gobierno, personal de la Administraci\u00f3n 2018-2021, a trav\u00e9s de la Direcci\u00f3n de Participaci\u00f3n Ciudadana, conformaron el comit\u00e9 n\u00famero 21 con el fin de ir trabajando en las principales necesidades de este sector y resolverlas a la brevedad posible. Carlos Rafael Rodr\u00edguez G\u00f3mez, Secretario de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":9175,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[461,664],"class_list":["post-9174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","tag-carlos-rafael-rodriguez-gomez","tag-comites-ciudadanos"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/9174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=9174"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/9174\/revisions"}],"predecessor-version":[{"id":67885,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/9174\/revisions\/67885"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=9174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=9174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=9174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}