                       {"id":9384,"date":"2019-08-01T18:20:43","date_gmt":"2019-08-01T23:20:43","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=9384"},"modified":"2024-12-11T08:56:05","modified_gmt":"2024-12-11T14:56:05","slug":"vendedores-estaban-advertidos-tesorero","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/vendedores-estaban-advertidos-tesorero\/","title":{"rendered":"\u201cVendedores estaban  advertidos\u201d: Tesorero"},"content":{"rendered":"<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9385 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/08\/41f8e2fa-d591-4a61-bf63-92d5007fa0b9-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/>Miguel Oscar P\u00e9rez<br \/>\nCADEREYTA JIM\u00c9NEZ, N.L.-<br \/>\nEl tesorero municipal, Juan Bautista Gonz\u00e1lez Franco, destac\u00f3 que desde el pasado cinco de abril, el municipio notific\u00f3 a los vendedores ambulantes, que no subieran los triciclos arriba de la plaza, m\u00e1s estos desafiaron a las autoridades, y continuaban en rebeld\u00eda, por eso se orden\u00f3 el operativo.<br \/>\n\u201cDesde el cinco de abril, les hicimos llegar un oficio, donde les pedimos que acataran el reglamento, en el reglamento les indicamos a estas personas que no pueden estar sobre la plaza p\u00fablica, desde entonces los estuvimos conminando que no vendieran en la v\u00eda p\u00fablica, espec\u00edficamente sobre la plaza\u201d, explic\u00f3 el tesorero.<br \/>\nSin embargo, se hizo caso omiso a la recomendaci\u00f3n y se procedi\u00f3 por medio de un operativo a levantar los triciclos, que por cierto son de un solo due\u00f1o y dos carretillas con botanas a granel.<br \/>\nCabe mencionar que las personas que operan los triciclos son de varios puntos del sur de la rep\u00fablica y solamente son trabajadores, ya que es de un propietario desconocido hasta hoy.<br \/>\nTrascendi\u00f3 adem\u00e1s que dentro de los vendedores ambulantes, hab\u00eda un menor de edad, que era puesto a trabajar y se proceder\u00e1 a investigarse si est\u00e1 estudiando y quien es la persona que lo tiene trabajando.<br \/>\nMencion\u00f3 el tesorero que dentro del ordenamiento que se busca en el comercio, tambi\u00e9n van por los comerciantes establecidos que ocupan las banquetas con los productos y ser\u00e1n obligados a pagar piso por ocupar un espacio p\u00fablico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miguel Oscar P\u00e9rez CADEREYTA JIM\u00c9NEZ, N.L.- El tesorero municipal, Juan Bautista Gonz\u00e1lez Franco, destac\u00f3 que desde el pasado cinco de abril, el municipio notific\u00f3 a los vendedores ambulantes, que no subieran los triciclos arriba de la plaza, m\u00e1s estos desafiaron a las autoridades, y continuaban en rebeld\u00eda, por eso se orden\u00f3 el operativo. \u201cDesde el [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":9385,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[1349,1991],"class_list":["post-9384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-cadereyta","tag-juan-bautista-gonzalez","tag-retiro-de-ambulantes-en-cadereyta"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/9384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=9384"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/9384\/revisions"}],"predecessor-version":[{"id":67995,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/9384\/revisions\/67995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=9384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=9384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=9384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}