                       {"id":9817,"date":"2019-08-22T20:18:26","date_gmt":"2019-08-23T01:18:26","guid":{"rendered":"http:\/\/laultimapalabra.info\/?p=9817"},"modified":"2024-12-11T08:56:11","modified_gmt":"2024-12-11T14:56:11","slug":"matar-a-nadie-recuerda-a-marlen","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/matar-a-nadie-recuerda-a-marlen\/","title":{"rendered":"\u201cMatar a nadie\u201d, recuerda a Marlen"},"content":{"rendered":"<p style=\"text-align: justify;\">Monterrey, 1978-Ciudad Benito Ju\u00e1rez, 2014<\/p>\n<p style=\"text-align: justify;\">Asesinada con arma blanca.<br \/>\nUn sentenciado.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9820 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/08\/542742_10150628980027623_2084766440_n-300x171.jpg\" alt=\"\" width=\"300\" height=\"171\" \/> \u00a0Por: Alba Calder\u00f3n<br \/>\nAunque su mayor miedo eran los asaltantes, Marlen Valdez Gracia enfrent\u00f3 al que ser\u00eda su asesino: Julio C\u00e9sar Guti\u00e9rrez, El Chucky, cuando persegu\u00eda a su vecina Gabriela M\u00e1rquez para robarle el celular.<br \/>\nMarlen dio refugio a la joven en su casa pero no logr\u00f3 evitar que entrara el Chucky, un adicto a los solventes de 21 a\u00f1os. Cuando lo encar\u00f3, la apu\u00f1al\u00f3 en el cuello y huy\u00f3. Denise, vecina tambi\u00e9n de la colonia Real de San Jos\u00e9, en Ciudad Benito Ju\u00e1rez, llam\u00f3 a emergencias. Luego contar\u00eda extra\u00f1ada que la ambulancia municipal tard\u00f3 casi 30 minutos en llegar, que los param\u00e9dicos llevaban uniforme de polic\u00edas, y que aunque Marlen se desangraba, no hicieron nada para detener la hemorragia.<br \/>\nA cinco minutos estaba la Unidad de Medicina Familiar 20 del IMSS, pero optaron por llevarla a la Cl\u00ednica Virginia, en Cadereyta, a m\u00e1s de 15 minutos. Marlen ingres\u00f3 al hospital sin signos vitales.<br \/>\n\u201cA m\u00ed no se me hubiera muerto\u201d, asegura Miguel \u00d3scar P\u00e9rez, su jefe de informaci\u00f3n en el semanario La \u00daltima Palabra de Cadereyta, donde Marlen trabajaba desde hac\u00eda cuatro a\u00f1os.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9819 alignright\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/08\/430556_10150560678132623_1820351258_n-213x300.jpg\" alt=\"\" width=\"213\" height=\"300\" \/>Lleg\u00f3 al lugar del ataque cuando la ambulancia ya hab\u00eda partido. No puede olvidar ese 20 de agosto de 2014, la sangre en la banqueta, una muerte que considera absurda.<br \/>\nDefine a Marlen como una reportera hiperactiva, rebelde, severa en sus cuestionamientos a los funcionarios. \u201cCasi de todo hac\u00eda notas; ten\u00edamos que dejar fuera mucho de su material\u201d.<br \/>\nLo mismo pod\u00eda narrar, frente a la c\u00e1mara, la historia del cl\u00e1sico corrido Laurita Garza que escribir un reportaje sobre corrupci\u00f3n. Un mes antes de su asesinato denunci\u00f3 que el cabildo de Ju\u00e1rez hab\u00eda adjudicado irregularmente un contrato por 32.2 millones de pesos a Ralmica Constructora para obras de repavimentaci\u00f3n que no se hab\u00edan realizado. Se\u00f1alaba como responsables a funcionarios del alcalde panista Rodolfo Ambriz.<br \/>\nMarlen escrib\u00eda tambi\u00e9n sobre su equipo de b\u00e9isbol favorito, Los Sultanes de Monterrrey, para el diario El Regio, y era cronista de los juegos de la liga municipal de San Nicol\u00e1s de los Garza.<br \/>\nEn 2011 fund\u00f3 en su casa el proyecto \u201cSue\u00f1os de Ni\u00f1os\u201d, con el que becaba a estudiantes y entregaba despensas o materiales m\u00e9dicos a personas de escasos recursos. Consegu\u00eda apoyos con funcionarios municipales y entre sus amigos.<br \/>\nGabriela Garc\u00eda trabaj\u00f3 junto a Marlen en el semanario La Espiga de Santa Catarina. Recuerda que era perseverante, franca y de car\u00e1cter fuerte. \u201cTen\u00eda sus metas muy fijas: \u2018me quiero ir de viaje a esta parte, quiero sacar esta nota\u2019\u201d, cuenta sobre su amiga.<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9821 alignleft\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/08\/575155_10150667694362623_1532863990_n-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" \/><br \/>\nMarlen era la mayor de dos hermanos. Gloria, su madre, no quer\u00eda que fuera periodista. \u201cEn mi rancho dicen que por estudiar eso te piden los jefes algo m\u00e1s\u201d, le advert\u00eda.<br \/>\nCurs\u00f3 primero una carrera t\u00e9cnica de comercio, por petici\u00f3n de Gloria, y despu\u00e9s se inscribi\u00f3 en la Universidad Metropolitana de Monterrey para estudiar periodismo. Antes de terminar la carrera en 2005, inici\u00f3 sus pr\u00e1cticas profesionales como locutora en una estaci\u00f3n de radio, luego trabaj\u00f3 un tiempo para TV Azteca.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9822 alignright\" src=\"https:\/\/laultimapalabra.com.mx\/portal\/wp-content\/uploads\/2019\/08\/912268_544786698905148_1797461811_n-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" \/>Era soltera, con casa propia, pero dorm\u00eda todos los d\u00edas con su mam\u00e1. A veces, Gloria viajaba hasta hora y media en transporte p\u00fablico para no dejarla sola. \u201cTen\u00eda mucho miedo a los rateros\u201d, recuerda entre l\u00e1grimas.<br \/>\nUn a\u00f1o despu\u00e9s del crimen, El Chucky fue declarado inimputable por considerar que la droga que consum\u00eda le produjo esquizofrenia. Se le sentenci\u00f3 a 20 a\u00f1os de tratamiento psiqui\u00e1trico en el Cereso de Cadereyta.<br \/>\nGabriela y Marlen dejaban el miedo atr\u00e1s en sus coberturas: \u201c\u00a1Si nos toca nos toca!\u201d, dec\u00edan. Todo cambi\u00f3 con el asesinato: \u201c\u00bfCon qu\u00e9 seguridad te puedes mover si terminan matando a una mujer que defiende a otra?\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monterrey, 1978-Ciudad Benito Ju\u00e1rez, 2014 Asesinada con arma blanca. Un sentenciado. \u00a0Por: Alba Calder\u00f3n Aunque su mayor miedo eran los asaltantes, Marlen Valdez Gracia enfrent\u00f3 al que ser\u00eda su asesino: Julio C\u00e9sar Guti\u00e9rrez, El Chucky, cuando persegu\u00eda a su vecina Gabriela M\u00e1rquez para robarle el celular. Marlen dio refugio a la joven en su casa [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":9818,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,10],"tags":[1502],"class_list":["post-9817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","category-seguridad-juarez","tag-marlen-valdez"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/9817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=9817"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/9817\/revisions"}],"predecessor-version":[{"id":68221,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/9817\/revisions\/68221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=9817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=9817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=9817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}