                       {"id":98202,"date":"2025-01-17T16:04:04","date_gmt":"2025-01-17T22:04:04","guid":{"rendered":"https:\/\/laultimapalabra.com.mx\/portal\/?p=98202"},"modified":"2025-01-17T16:04:04","modified_gmt":"2025-01-17T22:04:04","slug":"c4e-p3z-gord0-con-arm3s-y-explo5ivos","status":"publish","type":"post","link":"https:\/\/laultimapalabra.com.mx\/portal\/c4e-p3z-gord0-con-arm3s-y-explo5ivos\/","title":{"rendered":"C4e &#8220;p3z gord0&#8221; con arm3s y explo5ivos"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Ju\u00e1rez, N.L.-Desde la noche de ayer se present\u00f3 una intensa movilizaci\u00f3n en la colonia Arcadia la Silla en el municipio de Ju\u00e1rez, esto despu\u00e9s de que se diera un cateo en un domicilio de la mencionada colonia.<br \/>\nFue a partir de las 19:00 horas, que vecinos del lugar mandaron mensajes a nuestra p\u00e1gina preguntando sobre la movilizaci\u00f3n en la calle Alfredo Dieck, en donde se encontraban unidades del Ej\u00e9rcito Mexicano, Polic\u00eda Fuerza Civil y Agentes ministeriales, quienes ten\u00edan cerrada esta zona.<br \/>\nDicho cateo termin\u00f3 alrededor de las 20:00 horas, y el domicilio fue asegurado por la fiscal\u00eda desconoci\u00e9ndose hasta el momento cu\u00e1les fueron los resultados de esta operaci\u00f3n.<br \/>\nAs\u00ed mismo la misma noche de ayer se dio otra movilizaci\u00f3n en la calle Cima de la colonia Monte Alto, l\u00edmites de Ju\u00e1rez con Guadalupe, en donde se realiz\u00f3 otro cateo pero con resultados de mas impacto ya que seg\u00fan una fuente, en este lugar fue detenido un jefe de plaza y asegurado fuerte armamento y explosivos en dicho domicilio.<br \/>\nHasta el momento se desconoce la cifra de los detenidos y los resultados de dichas detenciones y cateos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Ju\u00e1rez, N.L.-Desde la noche de ayer se present\u00f3 una intensa movilizaci\u00f3n en la colonia Arcadia la Silla en el municipio de Ju\u00e1rez, esto despu\u00e9s de que se diera un cateo en un domicilio de la mencionada colonia. Fue a partir de las 19:00 horas, que vecinos del lugar mandaron mensajes a nuestra p\u00e1gina preguntando [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":98186,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[499,12679,3590,12680],"class_list":["post-98202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-locales-juarez","tag-cateo-juarez","tag-colonia-arcadia-la-silla","tag-juarez-nl","tag-pez-gordo"],"_links":{"self":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/98202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=98202"}],"version-history":[{"count":1,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/98202\/revisions"}],"predecessor-version":[{"id":98203,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/posts\/98202\/revisions\/98203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media\/98186"}],"wp:attachment":[{"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=98202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=98202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laultimapalabra.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=98202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}